{"id":101,"date":"2015-10-26T00:00:00","date_gmt":"2015-10-26T00:00:00","guid":{"rendered":"https:\/\/blog.engoo.com\/th\/2015\/10\/26\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/"},"modified":"2023-01-05T06:27:43","modified_gmt":"2023-01-05T06:27:43","slug":"%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88","status":"publish","type":"post","link":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/","title":{"rendered":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23"},"content":{"rendered":"<p>\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e1a\u0e46 \u0e2b\u0e31\u0e48\u0e19\u0e46 \u0e27\u0e48\u0e32\u0e21\u0e35\u0e2d\u0e30\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e27\u0e48\u0e32\u0e41\u0e25\u0e49\u0e27\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e40\u0e25\u0e22\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">Mince (\u0e21\u0e34\u0e19\u0e0b)<\/span> - \u0e2a\u0e31\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e1a\u0e14 \u0e40\u0e0a\u0e48\u0e19 \u0e2b\u0e21\u0e39\u0e2a\u0e31\u0e1a \u0e42\u0e14\u0e22\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e25\u0e2d\u0e07\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e21\u0e39\u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e27\u0e31\u0e27\u0e1a\u0e14\u0e17\u0e35\u0e48\u0e0b\u0e38\u0e1b\u0e40\u0e1b\u0e2d\u0e23\u0e4c\u0e21\u0e32\u0e40\u0e01\u0e47\u0e15 \u0e08\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1a\u0e19\u0e41\u0e1e\u0e04\u0e40\u0e01\u0e08\u0e27\u0e48\u0e32 minced pork \u0e2b\u0e23\u0e37\u0e2d minced beef<\/p>\n<p><span style=\"background-color:#AFEEEE\">Peel (\u0e1e\u0e35\u0e25)<\/span> - \u0e1b\u0e2d\u0e01 \u0e40\u0e0a\u0e48\u0e19 \u0e01\u0e32\u0e23\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e1c\u0e25\u0e44\u0e21\u0e49 \u0e22\u0e01\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07 My mother always peels apples before eating or cooking. \u0e41\u0e21\u0e48\u0e02\u0e2d\u0e07\u0e09\u0e31\u0e19\u0e21\u0e31\u0e01\u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e41\u0e2d\u0e1b\u0e40\u0e1b\u0e34\u0e25\u0e01\u0e48\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e08\u0e30\u0e19\u0e33\u0e44\u0e1b\u0e01\u0e34\u0e19\u0e2b\u0e23\u0e37\u0e2d\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23<\/p>\n<p>\u00a0<\/p>\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e01\u0e47\u0e15\u0e32\u0e21 \u0e16\u0e49\u0e32 peel \u0e43\u0e19\u0e23\u0e39\u0e1b\u0e02\u0e2d\u0e07\u0e04\u0e33\u0e19\u0e32\u0e21\u0e08\u0e30\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01 \u0e40\u0e0a\u0e48\u0e19 banana peel (\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e01\u0e25\u0e49\u0e27\u0e22) \u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e43\u0e0a\u0e49 skin \u0e01\u0e47\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e2b\u0e21\u0e37\u0e2d\u0e19\u0e01\u0e31\u0e19<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">Trim (\u0e17\u0e23\u0e34\u0e21)<\/span> - \u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07 \u0e40\u0e0a\u0e48\u0e19 Several years ago, I learned how to trim the fat off meat from watching my favorite TV program. \u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e35\u0e01\u0e48\u0e2d\u0e19 \u0e09\u0e31\u0e19\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e27\u0e34\u0e18\u0e35\u0e15\u0e31\u0e14\u0e41\u0e15\u0e48\u0e07\u0e44\u0e02\u0e21\u0e31\u0e19\u0e2d\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2a\u0e31\u0e15\u0e27\u0e4c\u0e08\u0e32\u0e01\u0e23\u0e32\u0e22\u0e01\u0e32\u0e23\u0e17\u0e35\u0e27\u0e35\u0e42\u0e1b\u0e23\u0e14<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">Chop (\u0e0a\u0e2d\u0e1b)<\/span> - \u0e2a\u0e31\u0e1a \u0e40\u0e0a\u0e48\u0e19 Chop up the onions and carrots roughly. \u0e2a\u0e31\u0e1a\u0e2b\u0e31\u0e27\u0e2b\u0e2d\u0e21\u0e41\u0e25\u0e30\u0e41\u0e04\u0e23\u0e2d\u0e17\u0e2b\u0e22\u0e32\u0e1a\u0e46<\/p>\n<p>\u200b<\/p>\n<p><span style=\"background-color:#AFEEEE\">Dice (\u0e44\u0e14\u0e0b)<\/span> - \u0e2b\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e25\u0e39\u0e01\u0e40\u0e15\u0e4b\u0e32\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e40\u0e0a\u0e48\u0e19 Peel and dice the potatoes then put into the pot. \u0e1b\u0e2d\u0e01\u0e40\u0e1b\u0e25\u0e37\u0e2d\u0e01\u0e21\u0e31\u0e19\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e41\u0e25\u0e30\u0e2b\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e2a\u0e35\u0e48\u0e40\u0e2b\u0e25\u0e35\u0e48\u0e22\u0e21\u0e25\u0e39\u0e01\u0e40\u0e15\u0e4b\u0e32\u0e40\u0e25\u0e47\u0e01\u0e46 \u0e08\u0e32\u0e01\u0e19\u0e31\u0e49\u0e19\u0e43\u0e2a\u0e48\u0e25\u0e07\u0e43\u0e19\u0e2b\u0e21\u0e49\u0e2d \u00a0<\/p>\n<p>\u00a0<\/p>\n<p>\u0e42\u0e14\u0e22 dice \u0e17\u0e35\u0e48\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e19\u0e32\u0e21 \u0e08\u0e30\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32\u0e25\u0e39\u0e01\u0e40\u0e15\u0e4b\u0e32\u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">Slice (\u0e2a\u0e44\u0e25\u0e0b)<\/span> - \u00a0\u0e40\u0e09\u0e37\u0e2d\u0e19 \u0e41\u0e25\u0e48 \u0e1d\u0e32\u0e19 \u0e2b\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e40\u0e0a\u0e48\u0e19 Please slice the tomatoes. \u0e0a\u0e48\u0e27\u0e22\u0e2b\u0e31\u0e48\u0e19\u0e21\u0e30\u0e40\u0e02\u0e37\u0e2d\u0e40\u0e17\u0e28\u0e40\u0e1b\u0e47\u0e19\u0e0a\u0e34\u0e49\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e43\u0e2b\u0e49\u0e2b\u0e19\u0e48\u0e2d\u0e22<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">Cut into strips (\u0e04\u0e31\u0e17 \u0e2d\u0e34\u0e19\u0e17\u0e39 \u0e2a\u0e15\u0e23\u0e34\u0e1b\u0e2a)<\/span> \u0e2b\u0e31\u0e48\u0e19\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e46 \u0e40\u0e0a\u0e48\u0e19 If you want to cut vegetables into thin strips you need a sharp knife. \u0e16\u0e49\u0e32\u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e08\u0e30\u0e2b\u0e31\u0e48\u0e19\u0e1c\u0e31\u0e01\u0e43\u0e2b\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e2a\u0e49\u0e19\u0e1a\u0e32\u0e07\u0e46 \u0e04\u0e38\u0e13\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e21\u0e35\u0e14\u0e04\u0e21\u0e46<\/p>\n<p>\n\u0e17\u0e35\u0e19\u0e35\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e02\u0e49\u0e32\u0e04\u0e23\u0e31\u0e27\u0e04\u0e07\u0e19\u0e36\u0e01\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e44\u0e27\u0e49\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e41\u0e25\u0e49\u0e27\u0e43\u0e0a\u0e48\u0e44\u0e2b\u0e21\u0e25\u0e48\u0e30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15...<\/p>\n","protected":false},"author":420,"featured_media":102,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"unified_meta_tagline_field":"","footnotes":""},"categories":[7],"tags":[10,17],"class_list":["post-101","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-7","tag-10","tag-17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engoo.co.th\/blog\/\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\/\u0e1b\u0e2d\u0e01-\u0e2b\u0e31\u0e48\u0e19-\u0e1c\u0e48\u0e32-\u0e1d\u0e32\u0e19-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"og:description\" content=\"\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e1a...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engoo.co.th\/blog\/\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\/\u0e1b\u0e2d\u0e01-\u0e2b\u0e31\u0e48\u0e19-\u0e1c\u0e48\u0e32-\u0e1d\u0e32\u0e19-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-26T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-05T06:27:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"niicha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"niicha\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/\"},\"author\":{\"name\":\"niicha\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\"},\"headline\":\"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23\",\"datePublished\":\"2015-10-26T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:27:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/\"},\"wordCount\":86,\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png\",\"keywords\":[\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\",\"\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\"],\"articleSection\":[\"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/\",\"name\":\"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png\",\"datePublished\":\"2015-10-26T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:27:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png\",\"width\":739,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Engoo\",\"item\":\"https:\/\/engoo.co.th\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\",\"item\":\"https:\/\/engoo.co.th\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\",\"item\":\"https:\/\/engoo.co.th\/blog\/category\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"description\":\"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/engoo.co.th\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\",\"name\":\"niicha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"contentUrl\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"caption\":\"niicha\"},\"sameAs\":[\"eye.engoochallenge@gmail.com\u00a0\"],\"url\":\"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engoo.co.th\/blog\/\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\/\u0e1b\u0e2d\u0e01-\u0e2b\u0e31\u0e48\u0e19-\u0e1c\u0e48\u0e32-\u0e1d\u0e32\u0e19-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","og_description":"\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e27\u0e48\u0e32\u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e17\u0e33\u0e2d\u0e32\u0e2b\u0e32\u0e23 \u0e41\u0e25\u0e30\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e08\u0e31\u0e14\u0e01\u0e32\u0e23\u0e27\u0e31\u0e15\u0e16\u0e38\u0e14\u0e34\u0e1a\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23 \u0e41\u0e15\u0e48\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e46 \u0e1a\u0e32\u0e07\u0e04\u0e19\u0e2d\u0e32\u0e08\u0e22\u0e31\u0e07\u0e44\u0e21\u0e48\u0e23\u0e39\u0e49\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a \u0e01\u0e32\u0e23\u0e2a\u0e31\u0e1a...","og_url":"https:\/\/engoo.co.th\/blog\/\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\/\u0e1b\u0e2d\u0e01-\u0e2b\u0e31\u0e48\u0e19-\u0e1c\u0e48\u0e32-\u0e1d\u0e32\u0e19-\u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\/","og_site_name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","article_published_time":"2015-10-26T00:00:00+00:00","article_modified_time":"2023-01-05T06:27:43+00:00","og_image":[{"width":739,"height":388,"url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png","type":"image\/png"}],"author":"niicha","twitter_card":"summary_large_image","twitter_misc":{"Written by":"niicha"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#article","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/"},"author":{"name":"niicha","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5"},"headline":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23","datePublished":"2015-10-26T00:00:00+00:00","dateModified":"2023-01-05T06:27:43+00:00","mainEntityOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/"},"wordCount":86,"publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png","keywords":["\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c","\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19"],"articleSection":["\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/","url":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/","name":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png","datePublished":"2015-10-26T00:00:00+00:00","dateModified":"2023-01-05T06:27:43+00:00","breadcrumb":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#primaryimage","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083257\/big_26.10.15-engoo.png","width":739,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/engoo.co.th\/blog\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/%e0%b8%9b%e0%b8%ad%e0%b8%81-%e0%b8%ab%e0%b8%b1%e0%b9%88%e0%b8%99-%e0%b8%9c%e0%b9%88%e0%b8%b2-%e0%b8%9d%e0%b8%b2%e0%b8%99-%e0%b8%ad%e0%b8%b2%e0%b8%ab%e0%b8%b2%e0%b8%a3%e0%b9%81%e0%b8%95%e0%b9%88\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Engoo","item":"https:\/\/engoo.co.th"},{"@type":"ListItem","position":2,"name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01","item":"https:\/\/engoo.co.th\/blog\/"},{"@type":"ListItem","position":3,"name":"\u0e40\u0e17\u0e04\u0e19\u0e34\u0e04\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29","item":"https:\/\/engoo.co.th\/blog\/category\/%e0%b9%80%e0%b8%97%e0%b8%84%e0%b8%99%e0%b8%b4%e0%b8%84%e0%b8%a0%e0%b8%b2%e0%b8%a9%e0%b8%b2%e0%b8%ad%e0%b8%b1%e0%b8%87%e0%b8%81%e0%b8%a4%e0%b8%a9\/"},{"@type":"ListItem","position":4,"name":"\u0e1b\u0e2d\u0e01 \u0e2b\u0e31\u0e48\u0e19 \u0e1c\u0e48\u0e32 \u0e1d\u0e32\u0e19 \u0e2d\u0e32\u0e2b\u0e32\u0e23\u0e41\u0e15\u0e48\u0e25\u0e30\u0e0a\u0e19\u0e34\u0e14 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23"}]},{"@type":"WebSite","@id":"https:\/\/engoo.co.th\/blog\/#website","url":"https:\/\/engoo.co.th\/blog\/","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","description":"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engoo.co.th\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/engoo.co.th\/blog\/#organization","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","url":"https:\/\/engoo.co.th\/blog\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","width":1,"height":1,"caption":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5","name":"niicha","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","contentUrl":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","caption":"niicha"},"sameAs":["eye.engoochallenge@gmail.com\u00a0"],"url":"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/"}]}},"_links":{"self":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/101","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/users\/420"}],"replies":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/comments?post=101"}],"version-history":[{"count":1,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions"}],"predecessor-version":[{"id":719,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/101\/revisions\/719"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media\/102"}],"wp:attachment":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media?parent=101"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/categories?post=101"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/tags?post=101"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}