{"id":53,"date":"2015-09-13T00:00:00","date_gmt":"2015-09-13T00:00:00","guid":{"rendered":"https:\/\/blog.engoo.com\/th\/2015\/09\/13\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/"},"modified":"2023-01-05T06:28:20","modified_gmt":"2023-01-05T06:28:20","slug":"5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c","status":"publish","type":"post","link":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/","title":{"rendered":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14"},"content":{"rendered":"<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e2d\u0e32\u0e44\u0e1b\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e07\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e14\u0e35\u0e01\u0e27\u0e48\u0e32 \u0e27\u0e48\u0e32\u0e04\u0e33\u0e44\u0e2b\u0e19\u0e17\u0e35\u0e48\u0e04\u0e19\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\u0e01\u0e31\u0e19\u0e1a\u0e49\u0e32\u0e07<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">1. <\/span><strong>receipt<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e43\u0e1a\u0e40\u0e2a\u0e23\u0e47\u0e08 \u0e04\u0e33\u0e1b\u0e23\u0e32\u0e1a\u0e40\u0e0b\u0e35\u0e22\u0e19\u0e04\u0e33\u0e19\u0e35\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e48\u0e32 <\/span><strong>\u0e23\u0e35\u0e0b\u0e35\u0e17<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 <\/span><strong>\u0e23\u0e35\u0e0b\u0e35\u0e1e\u0e17\u0e4c<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\u0e46 \u0e01\u0e31\u0e19\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e33\u0e19\u0e35\u0e49\u0e44\u0e21\u0e48\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27 p \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">2. <\/span><strong>debt<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e2b\u0e19\u0e35\u0e49 \u0e2a\u0e32\u0e23\u0e20\u0e32\u0e1e\u0e21\u0e32\u0e0b\u0e30\u0e14\u0e35\u0e46 \u0e27\u0e48\u0e32\u0e17\u0e38\u0e01\u0e04\u0e19\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e48\u0e32<\/span><strong> \u0e40\u0e14\u0e47\u0e1a\u0e17\u0e4c<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e21\u0e32\u0e42\u0e14\u0e22\u0e15\u0e25\u0e2d\u0e14 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e37\u0e2d <\/span><strong>\u0e40\u0e14\u0e47\u0e17<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e04\u0e33\u0e19\u0e35\u0e49\u0e15\u0e49\u0e2d\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27 b \u0e19\u0e30\u0e08\u0e4a\u0e30<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">3. <\/span><strong>elephant<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e0a\u0e49\u0e32\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e0a\u0e2d\u0e1a\u0e2d\u0e48\u0e32\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e40\u0e25\u0e02 11 \u0e27\u0e48\u0e32 <\/span><strong>\u0e2d\u0e34\u0e40\u0e25\u0e1f\u0e40\u0e1f\u0e48\u0e19<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e0b\u0e36\u0e48\u0e07\u0e01\u0e47\u0e1c\u0e34\u0e14\u0e44\u0e1b\u0e15\u0e32\u0e21\u0e23\u0e30\u0e40\u0e1a\u0e35\u0e22\u0e1a \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e37\u0e2d <\/span><strong>\u0e40\u0e2d\u0e25\u0e34\u0e40\u0e1d\u0e34\u0e48\u0e19\u0e17 <\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01 \u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15\u0e2d\u0e35\u0e01\u0e17\u0e35\u0e27\u0e48\u0e32 <\/span><strong>\u0e40\u0e2d<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e44\u0e21\u0e48\u0e43\u0e0a\u0e48 <\/span><strong>\u0e2d\u0e34<\/strong><\/span><\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">4. <\/span><strong>salmon<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e2b\u0e23\u0e37\u0e2d\u0e40\u0e21\u0e19\u0e39\u0e1b\u0e25\u0e32\u0e08\u0e32\u0e19\u0e42\u0e1b\u0e23\u0e14\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23\u0e2b\u0e25\u0e32\u0e22\u0e46 \u0e04\u0e19 \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e17\u0e31\u0e49\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e31\u0e49\u0e07\u0e40\u0e02\u0e35\u0e22\u0e19\u0e1c\u0e34\u0e14\u0e01\u0e31\u0e19\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14\u0e27\u0e48\u0e32 <\/span><strong>\u0e41\u0e0b\u0e25\u0e21\u0e2d\u0e19<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e08\u0e23\u0e34\u0e07\u0e46 \u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e48\u0e32\u0e19\u0e40\u0e1b\u0e47\u0e19 <\/span><strong>\u0e41\u0e0b\u0e40\u0e21\u0e34\u0e19<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e40\u0e02\u0e32\u0e44\u0e21\u0e48\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e15\u0e31\u0e27 l \u0e01\u0e31\u0e19<\/span><\/span><\/p>\n<p>\u00a0<\/p>\n<p dir=\"ltr\"><span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">5. <\/span><strong>slave <\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">\u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e17\u0e32\u0e2a \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e15\u0e34\u0e14\u0e1b\u0e32\u0e01\u0e08\u0e32\u0e01\u0e40\u0e01\u0e21\u0e17\u0e35\u0e48\u0e0a\u0e2d\u0e1a\u0e40\u0e25\u0e48\u0e19\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32 <\/span><strong>\u0e2a\u0e25\u0e32\u0e1f<\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\"> \u0e17\u0e35\u0e48\u0e16\u0e39\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e04\u0e37\u0e2d\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e48\u0e32<\/span><strong> \u0e2a\u0e40\u0e25\u0e1f <\/strong><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">\u0e15\u0e48\u0e32\u0e07\u0e2b\u0e32\u0e01\u0e25\u0e48\u0e30 \u0e08\u0e33\u0e44\u0e27\u0e49\u0e43\u0e2b\u0e49\u0e14\u0e35<\/span><\/span><\/p>\n<p>\n<span style=\"font-size:24px\"><span style=\"background-color:transparent; color:rgb(0, 0, 0); font-family:thonburi\">\u0e23\u0e39\u0e49\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e27\u0e48\u0e32 5 \u0e04\u0e33\u0e19\u0e35\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e48\u0e32\u0e2d\u0e30\u0e44\u0e23 \u0e1e\u0e23\u0e38\u0e48\u0e07\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e15\u0e49\u0e19\u0e44\u0e1b\u0e04\u0e07\u0e44\u0e21\u0e48\u0e2d\u0e48\u0e32\u0e19\u0e1c\u0e34\u0e14\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27<\/span><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22...<\/p>\n","protected":false},"author":420,"featured_media":54,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"unified_meta_tagline_field":"","footnotes":""},"categories":[9],"tags":[14,10],"class_list":["post-53","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-9","tag-14","tag-10"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/5-\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"og:description\" content=\"\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e2d\u0e32\u0e44\u0e1b\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e07\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e14...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/5-\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"article:published_time\" content=\"2015-09-13T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-05T06:28:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"niicha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"niicha\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/\"},\"author\":{\"name\":\"niicha\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\"},\"headline\":\"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\",\"datePublished\":\"2015-09-13T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:28:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/\"},\"wordCount\":8,\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png\",\"keywords\":[\"\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\",\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\"],\"articleSection\":[\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/\",\"name\":\"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png\",\"datePublished\":\"2015-09-13T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:28:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png\",\"width\":739,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Engoo\",\"item\":\"https:\/\/engoo.co.th\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\",\"item\":\"https:\/\/engoo.co.th\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\",\"item\":\"https:\/\/engoo.co.th\/blog\/category\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"description\":\"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/engoo.co.th\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\",\"name\":\"niicha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"contentUrl\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"caption\":\"niicha\"},\"sameAs\":[\"eye.engoochallenge@gmail.com\u00a0\"],\"url\":\"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/5-\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\/","og_locale":"th_TH","og_type":"article","og_title":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","og_description":"\u0e23\u0e39\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e21\u0e35\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e1a\u0e32\u0e07\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14\u0e21\u0e32\u0e15\u0e25\u0e2d\u0e14 \u0e0b\u0e36\u0e48\u0e07\u0e1a\u0e2d\u0e01\u0e40\u0e25\u0e22\u0e27\u0e48\u0e32\u0e2b\u0e32\u0e01\u0e40\u0e2d\u0e32\u0e44\u0e1b\u0e1e\u0e39\u0e14\u0e01\u0e31\u0e1a\u0e1d\u0e23\u0e31\u0e48\u0e07\u0e15\u0e49\u0e2d\u0e07\u0e21\u0e35\u0e07\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19 \u0e16\u0e49\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e19\u0e31\u0e49\u0e19\u0e21\u0e32\u0e14\u0e39\u0e01\u0e31\u0e19\u0e14...","og_url":"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/5-\u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\/","og_site_name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","article_published_time":"2015-09-13T00:00:00+00:00","article_modified_time":"2023-01-05T06:28:20+00:00","og_image":[{"width":739,"height":388,"url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png","type":"image\/png"}],"author":"niicha","twitter_card":"summary_large_image","twitter_misc":{"Written by":"niicha"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#article","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/"},"author":{"name":"niicha","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5"},"headline":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14","datePublished":"2015-09-13T00:00:00+00:00","dateModified":"2023-01-05T06:28:20+00:00","mainEntityOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/"},"wordCount":8,"publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png","keywords":["\u0e01\u0e32\u0e23\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29","\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c"],"articleSection":["\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/","url":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/","name":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14 | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png","datePublished":"2015-09-13T00:00:00+00:00","dateModified":"2023-01-05T06:28:20+00:00","breadcrumb":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#primaryimage","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11082757\/big_01.09.15-engoo_1.png","width":739,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/5-%e0%b8%84%e0%b8%b3%e0%b8%97%e0%b8%b5%e0%b9%88%e0%b8%84%e0%b8%99%e0%b9%84%e0%b8%97%e0%b8%a2%e0%b8%a1%e0%b8%b1%e0%b8%81%e0%b8%ad%e0%b8%ad%e0%b8%81%e0%b9%80%e0%b8%aa%e0%b8%b5%e0%b8%a2%e0%b8%87%e0%b8%9c\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Engoo","item":"https:\/\/engoo.co.th"},{"@type":"ListItem","position":2,"name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01","item":"https:\/\/engoo.co.th\/blog\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22","item":"https:\/\/engoo.co.th\/blog\/category\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/"},{"@type":"ListItem","position":4,"name":"5 \u0e04\u0e33\u0e17\u0e35\u0e48\u0e04\u0e19\u0e44\u0e17\u0e22\u0e21\u0e31\u0e01\u0e2d\u0e2d\u0e01\u0e40\u0e2a\u0e35\u0e22\u0e07\u0e1c\u0e34\u0e14"}]},{"@type":"WebSite","@id":"https:\/\/engoo.co.th\/blog\/#website","url":"https:\/\/engoo.co.th\/blog\/","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","description":"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engoo.co.th\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/engoo.co.th\/blog\/#organization","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","url":"https:\/\/engoo.co.th\/blog\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","width":1,"height":1,"caption":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5","name":"niicha","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","contentUrl":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","caption":"niicha"},"sameAs":["eye.engoochallenge@gmail.com\u00a0"],"url":"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/"}]}},"_links":{"self":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/53","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/users\/420"}],"replies":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/comments?post=53"}],"version-history":[{"count":1,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/53\/revisions"}],"predecessor-version":[{"id":743,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/53\/revisions\/743"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media\/54"}],"wp:attachment":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media?parent=53"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/categories?post=53"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/tags?post=53"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}