{"id":95,"date":"2015-10-23T00:00:00","date_gmt":"2015-10-23T00:00:00","guid":{"rendered":"https:\/\/blog.engoo.com\/th\/2015\/10\/23\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/"},"modified":"2023-01-05T06:27:47","modified_gmt":"2023-01-05T06:27:47","slug":"%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1","status":"publish","type":"post","link":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/","title":{"rendered":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a"},"content":{"rendered":"<p>\u0e43\u0e04\u0e23\u0e46 \u0e01\u0e47\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a 23 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1f\u0e31\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e07\u0e19\u0e36\u0e01\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e01\u0e31\u0e19\u0e44\u0e21\u0e48\u0e2d\u0e2d\u0e01 \u0e27\u0e31\u0e19\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e40\u0e25\u0e22\u0e21\u0e35\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e21\u0e32\u0e1d\u0e32\u0e01\u0e01\u0e31\u0e19\u0e04\u0e48\u0e30<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a \u0e40\u0e23\u0e35\u0e22\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 Chulalongkorn Day<\/span> \u0e0b\u0e36\u0e48\u0e07\u0e41\u0e19\u0e48\u0e19\u0e2d\u0e19\u0e27\u0e48\u0e32\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2b\u0e22\u0e38\u0e14\u0e02\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e23\u0e32\u0e0a\u0e01\u0e32\u0e23 \u0e2b\u0e23\u0e37\u0e2d National holiday \u0e2b\u0e23\u0e37\u0e2d Public holiday \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p>\n<p>\u00a0<\/p>\n<p>\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e16\u0e37\u0e2d\u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e04\u0e25\u0e49\u0e32\u0e22\u0e27\u0e31\u0e19\u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15\u0e02\u0e2d\u0e07\u0e1e\u0e23\u0e30\u0e1a\u0e32\u0e17\u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e38\u0e25\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e40\u0e08\u0e49\u0e32\u0e2d\u0e22\u0e39\u0e48\u0e2b\u0e31\u0e27 \u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 5<\/p>\n<p><span style=\"background-color:#AFEEEE\">\u0e04\u0e33\u0e27\u0e48\u0e32 \u0e2a\u0e27\u0e23\u0e23\u0e04\u0e15 \u0e1e\u0e39\u0e14\u0e40\u0e1b\u0e47\u0e19\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e44\u0e14\u0e49\u0e27\u0e48\u0e32 pass away<\/span> \u0e42\u0e14\u0e22\u0e04\u0e33\u0e19\u0e35\u0e49\u0e40\u0e1b\u0e47\u0e19\u0e04\u0e33\u0e2a\u0e38\u0e20\u0e32\u0e1e\u0e17\u0e35\u0e48\u0e40\u0e23\u0e32\u0e19\u0e33\u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07\u0e01\u0e32\u0e23\u0e15\u0e32\u0e22\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e17\u0e31\u0e48\u0e27\u0e44\u0e1b\u0e44\u0e14\u0e49\u0e14\u0e49\u0e27\u0e22<\/p>\n<p>\u00a0<\/p>\n<p>\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e01\u0e31\u0e19\u0e27\u0e48\u0e32\u0e23\u0e31\u0e0a\u0e01\u0e32\u0e25\u0e17\u0e35\u0e48 5 \u0e17\u0e23\u0e07\u0e21\u0e35\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e23\u0e38\u0e13\u0e32\u0e18\u0e34\u0e04\u0e38\u0e13\u0e2d\u0e31\u0e19\u0e42\u0e14\u0e14\u0e40\u0e14\u0e48\u0e19\u0e15\u0e48\u0e2d\u0e0a\u0e32\u0e27\u0e44\u0e17\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e23 \u0e42\u0e14\u0e22\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e22\u0e34\u0e48\u0e07 \u0e01\u0e32\u0e23\u0e17\u0e23\u0e07\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e34\u0e01\u0e17\u0e32\u0e2a \u0e0b\u0e36\u0e48\u0e07\u0e2b\u0e32\u0e01\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e04\u0e33\u0e27\u0e48\u0e32 <span style=\"background-color:#AFEEEE\">\u201c\u0e40\u0e25\u0e34\u0e01\u0e17\u0e32\u0e2a\u201d<\/span> \u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1f\u0e31\u0e07 \u0e43\u0e2b\u0e49\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32 <span style=\"background-color:#AFEEEE\">abolition of slavery<\/span> (\u0e2d\u0e48\u0e32\u0e19\u0e27\u0e48\u0e32 \u0e41\u0e2d\u0e1a\u0e1a\u0e30\u0e25\u0e34\u0e0b\u0e40\u0e0a\u0e34\u0e19 \u0e2d\u0e2d\u0e1f \u0e2a\u0e40\u0e25\u0e40\u0e27\u0e2d\u0e23\u0e35) \u0e40\u0e0a\u0e48\u0e19<\/p>\n<p>King Chulalongkorn was best known for his abolition of Siamese slavery. \u0e2a\u0e21\u0e40\u0e14\u0e47\u0e08\u0e1e\u0e23\u0e30\u0e08\u0e38\u0e25\u0e08\u0e2d\u0e21\u0e40\u0e01\u0e25\u0e49\u0e32\u0e2f \u0e17\u0e23\u0e07\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e35\u0e48\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e14\u0e49\u0e32\u0e19\u0e01\u0e32\u0e23\u0e40\u0e25\u0e34\u0e01\u0e17\u0e32\u0e2a\u0e43\u0e2b\u0e49\u0e01\u0e31\u0e1a\u0e2a\u0e22\u0e32\u0e21\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p>\n<p>\u00a0<\/p>\n<p>\u0e2b\u0e23\u0e37\u0e2d\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e04\u0e33\u0e27\u0e48\u0e32 <span style=\"background-color:#AFEEEE\">announcement of Slave Abolition Act \u0e2b\u0e23\u0e37\u0e2d\u0e1b\u0e23\u0e30\u0e01\u0e32\u0e28\u0e40\u0e25\u0e34\u0e01\u0e17\u0e32\u0e2a<\/span> \u0e01\u0e47\u0e44\u0e14\u0e49<\/p>\n<p>\u00a0<\/p>\n<p>\u0e19\u0e2d\u0e01\u0e08\u0e32\u0e01\u0e19\u0e35\u0e49\u0e17\u0e48\u0e32\u0e19\u0e22\u0e31\u0e07\u0e17\u0e23\u0e07\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e23\u0e32\u0e0a\u0e2d\u0e32\u0e13\u0e32\u0e08\u0e31\u0e01\u0e23\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32\u0e44\u0e21\u0e48\u0e43\u0e2b\u0e49\u0e15\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e02\u0e36\u0e49\u0e19\u0e02\u0e2d\u0e07\u0e43\u0e04\u0e23 \u0e2b\u0e23\u0e37\u0e2d prevent Thailand from being colonized \u0e42\u0e14\u0e22\u0e04\u0e33\u0e27\u0e48\u0e32 <span style=\"background-color:#AFEEEE\">colonize \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e01\u0e32\u0e23\u0e15\u0e31\u0e49\u0e07\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21<\/span> \u0e2d\u0e22\u0e39\u0e48\u0e43\u0e19\u0e23\u0e39\u0e1b be+past participle \u0e40\u0e1e\u0e23\u0e32\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e37\u0e48\u0e2d\u0e16\u0e36\u0e07 passive \u0e2b\u0e23\u0e37\u0e2d \u0e01\u0e32\u0e23\u0e16\u0e39\u0e01\u0e01\u0e23\u0e30\u0e17\u0e33 (\u0e16\u0e39\u0e01\u0e25\u0e48\u0e32\u0e2d\u0e32\u0e13\u0e32\u0e19\u0e34\u0e04\u0e21) \u0e19\u0e31\u0e48\u0e19\u0e40\u0e2d\u0e07<\/p>\n<p>\u00a0<\/p>\n<p>\u0e2a\u0e48\u0e27\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e01\u0e23\u0e13\u0e35\u0e22\u0e01\u0e34\u0e08\u0e17\u0e35\u0e48\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e01\u0e47\u0e40\u0e0a\u0e48\u0e19<\/p>\n<p>improved postal services \u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e44\u0e1b\u0e23\u0e29\u0e13\u0e35\u0e22\u0e4c<\/p>\n<p>improved the telegraph \u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e23\u0e30\u0e1a\u0e1a\u0e42\u0e17\u0e23\u0e40\u0e25\u0e02<\/p>\n<p>improved the construction of Thailand\u2019s first railway \u0e01\u0e48\u0e2d\u0e15\u0e31\u0e49\u0e07\u0e17\u0e32\u0e07\u0e23\u0e16\u0e44\u0e1f\u0e2a\u0e32\u0e22\u0e41\u0e23\u0e01\u0e02\u0e2d\u0e07\u0e40\u0e21\u0e37\u0e2d\u0e07\u0e44\u0e17\u0e22<\/p>\n<p>\u00a0<\/p>\n<p>\u0e41\u0e25\u0e49\u0e27\u0e2b\u0e32\u0e01\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e16\u0e32\u0e21\u0e27\u0e48\u0e32 \u0e41\u0e25\u0e49\u0e27\u0e40\u0e23\u0e32\u0e17\u0e33\u0e41\u0e2a\u0e14\u0e07\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e40\u0e19\u0e37\u0e48\u0e2d\u0e07\u0e43\u0e19\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e27\u0e48\u0e32\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23\u0e1a\u0e49\u0e32\u0e07 \u0e01\u0e47\u0e43\u0e2b\u0e49\u0e15\u0e2d\u0e1a\u0e27\u0e48\u0e32<\/p>\n<p>\u00a0<\/p>\n<p>We respect for the great monarch by placing wreaths at the Equestrian Statue, in the Dusit Palace Plaza<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">wreath (\u0e23\u0e35\u0e18) \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32<\/span><\/p>\n<p><span style=\"background-color:#AFEEEE\">Equestrian Statue (\u0e2d\u0e35\u0e40\u0e04\u0e27\u0e2a\u0e40\u0e17\u0e23\u0e35\u0e22\u0e19 \u0e2a\u0e41\u0e15\u0e17\u0e34\u0e27) \u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e21\u0e49\u0e32<\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u0e1b\u0e23\u0e30\u0e42\u0e22\u0e04\u0e19\u0e35\u0e49\u0e08\u0e36\u0e07\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32<\/p>\n<p>\u00a0<\/p>\n<p>\u0e40\u0e23\u0e32\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e04\u0e32\u0e23\u0e1e\u0e1e\u0e23\u0e30\u0e21\u0e2b\u0e32\u0e01\u0e29\u0e31\u0e15\u0e23\u0e34\u0e22\u0e4c\u0e1c\u0e39\u0e49\u0e22\u0e34\u0e48\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e14\u0e49\u0e27\u0e22\u0e01\u0e32\u0e23\u0e27\u0e32\u0e07\u0e1e\u0e27\u0e07\u0e21\u0e32\u0e25\u0e32\u0e17\u0e35\u0e48\u0e1e\u0e23\u0e30\u0e1a\u0e23\u0e21\u0e23\u0e39\u0e1b\u0e17\u0e23\u0e07\u0e21\u0e49\u0e32 \u0e25\u0e32\u0e19\u0e1e\u0e23\u0e30\u0e23\u0e32\u0e0a\u0e27\u0e31\u0e07\u0e14\u0e38\u0e2a\u0e34\u0e15<\/p>\n<p>\u00a0<\/p>\n<p><span style=\"background-color:#AFEEEE\">* \u0e02\u0e49\u0e2d\u0e2a\u0e31\u0e07\u0e40\u0e01\u0e15 \u0e04\u0e33\u0e27\u0e48\u0e32 place \u0e17\u0e35\u0e48\u0e41\u0e1b\u0e25\u0e27\u0e48\u0e32 \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e07\u0e1a\u0e38\u0e1e\u0e1a\u0e17 by \u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e1b\u0e25\u0e35\u0e48\u0e22\u0e19\u0e23\u0e39\u0e1b\u0e40\u0e1b\u0e47\u0e19 v.ing \u0e42\u0e14\u0e22\u0e01\u0e34\u0e23\u0e34\u0e22\u0e32\u0e2a\u0e48\u0e27\u0e19\u0e43\u0e2b\u0e0d\u0e48\u0e2b\u0e32\u0e01\u0e15\u0e32\u0e21\u0e2b\u0e25\u0e31\u0e07 by \u0e15\u0e49\u0e2d\u0e07\u0e40\u0e15\u0e34\u0e21 ing \u0e40\u0e2a\u0e21\u0e2d<\/span><\/p>\n<p>\u00a0<\/p>\n<p>\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e40\u0e17\u0e48\u0e32\u0e19\u0e35\u0e49\u0e40\u0e23\u0e32\u0e01\u0e47\u0e23\u0e39\u0e49\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e17\u0e35\u0e48\u0e40\u0e1e\u0e35\u0e22\u0e07\u0e1e\u0e2d\u0e17\u0e35\u0e48\u0e08\u0e30\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e23\u0e39\u0e49\u0e08\u0e31\u0e01\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\u0e01\u0e31\u0e19\u0e41\u0e25\u0e49\u0e27\u0e25\u0e48\u0e30<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u0e43\u0e04\u0e23\u0e46 \u0e01\u0e47\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a 23 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21...<\/p>\n","protected":false},"author":420,"featured_media":96,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"unified_meta_tagline_field":"","footnotes":""},"categories":[9],"tags":[10,17],"class_list":["post-95","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-9","tag-10","tag-17"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"og:description\" content=\"\u0e43\u0e04\u0e23\u0e46 \u0e01\u0e47\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a 23 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1f\u0e31\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e07\u0e19\u0e36\u0e01\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e01\u0e31\u0e19\u0e44...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\/\" \/>\n<meta property=\"og:site_name\" content=\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-23T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-01-05T06:27:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"739\" \/>\n\t<meta property=\"og:image:height\" content=\"388\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"niicha\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"niicha\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/\"},\"author\":{\"name\":\"niicha\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\"},\"headline\":\"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\",\"datePublished\":\"2015-10-23T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:27:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/\"},\"wordCount\":78,\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png\",\"keywords\":[\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\",\"\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19\"],\"articleSection\":[\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\"],\"inLanguage\":\"th\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/\",\"name\":\"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"isPartOf\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png\",\"datePublished\":\"2015-10-23T00:00:00+00:00\",\"dateModified\":\"2023-01-05T06:27:47+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png\",\"width\":739,\"height\":388},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Engoo\",\"item\":\"https:\/\/engoo.co.th\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\",\"item\":\"https:\/\/engoo.co.th\/blog\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\",\"item\":\"https:\/\/engoo.co.th\/blog\/category\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#website\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"description\":\"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13\",\"publisher\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/engoo.co.th\/blog\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#organization\",\"name\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\",\"url\":\"https:\/\/engoo.co.th\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"contentUrl\":\"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg\",\"width\":1,\"height\":1,\"caption\":\"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39\"},\"image\":{\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5\",\"name\":\"niicha\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"contentUrl\":\"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg\",\"caption\":\"niicha\"},\"sameAs\":[\"eye.engoochallenge@gmail.com\u00a0\"],\"url\":\"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\/","og_locale":"th_TH","og_type":"article","og_title":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","og_description":"\u0e43\u0e04\u0e23\u0e46 \u0e01\u0e47\u0e23\u0e39\u0e49\u0e27\u0e48\u0e32\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a 23 \u0e15\u0e38\u0e25\u0e32\u0e04\u0e21\u0e02\u0e2d\u0e07\u0e17\u0e38\u0e01\u0e1b\u0e35 \u0e40\u0e1b\u0e47\u0e19\u0e27\u0e31\u0e19\u0e2a\u0e33\u0e04\u0e31\u0e0d\u0e02\u0e2d\u0e07\u0e04\u0e19\u0e44\u0e17\u0e22 \u0e41\u0e15\u0e48\u0e16\u0e49\u0e32\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e18\u0e34\u0e1a\u0e32\u0e22\u0e43\u0e2b\u0e49\u0e04\u0e19\u0e15\u0e48\u0e32\u0e07\u0e0a\u0e32\u0e15\u0e34\u0e1f\u0e31\u0e07 \u0e2b\u0e25\u0e32\u0e22\u0e04\u0e19\u0e04\u0e07\u0e19\u0e36\u0e01\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e01\u0e31\u0e19\u0e44...","og_url":"https:\/\/engoo.co.th\/blog\/\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22\/\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\/","og_site_name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","article_published_time":"2015-10-23T00:00:00+00:00","article_modified_time":"2023-01-05T06:27:47+00:00","og_image":[{"width":739,"height":388,"url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png","type":"image\/png"}],"author":"niicha","twitter_card":"summary_large_image","twitter_misc":{"Written by":"niicha"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#article","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/"},"author":{"name":"niicha","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5"},"headline":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a","datePublished":"2015-10-23T00:00:00+00:00","dateModified":"2023-01-05T06:27:47+00:00","mainEntityOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/"},"wordCount":78,"publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png","keywords":["\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c","\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e1b\u0e23\u0e30\u0e08\u0e33\u0e27\u0e31\u0e19"],"articleSection":["\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22"],"inLanguage":"th"},{"@type":"WebPage","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/","url":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/","name":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a | \u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","isPartOf":{"@id":"https:\/\/engoo.co.th\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage"},"thumbnailUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png","datePublished":"2015-10-23T00:00:00+00:00","dateModified":"2023-01-05T06:27:47+00:00","breadcrumb":{"@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#primaryimage","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/11083224\/big_23.10.15-engoo.png","width":739,"height":388},{"@type":"BreadcrumbList","@id":"https:\/\/engoo.co.th\/blog\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%84%e0%b8%a7%e0%b8%a3%e0%b8%a3%e0%b8%b9%e0%b9%89%e0%b9%80%e0%b8%81%e0%b8%b5%e0%b9%88%e0%b8%a2%e0%b8%a7%e0%b8%81%e0%b8%b1%e0%b8%9a%e0%b8%a7%e0%b8%b1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Engoo","item":"https:\/\/engoo.co.th"},{"@type":"ListItem","position":2,"name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01","item":"https:\/\/engoo.co.th\/blog\/"},{"@type":"ListItem","position":3,"name":"\u0e04\u0e33\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e0a\u0e27\u0e19\u0e2a\u0e07\u0e2a\u0e31\u0e22","item":"https:\/\/engoo.co.th\/blog\/category\/%e0%b8%84%e0%b8%b3%e0%b8%a8%e0%b8%b1%e0%b8%9e%e0%b8%97%e0%b9%8c%e0%b8%8a%e0%b8%a7%e0%b8%99%e0%b8%aa%e0%b8%87%e0%b8%aa%e0%b8%b1%e0%b8%a2\/"},{"@type":"ListItem","position":4,"name":"\u0e28\u0e31\u0e1e\u0e17\u0e4c\u0e04\u0e27\u0e23\u0e23\u0e39\u0e49\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e27\u0e31\u0e19\u0e1b\u0e34\u0e22\u0e21\u0e2b\u0e32\u0e23\u0e32\u0e0a"}]},{"@type":"WebSite","@id":"https:\/\/engoo.co.th\/blog\/#website","url":"https:\/\/engoo.co.th\/blog\/","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","description":"\u0e40\u0e04\u0e25\u0e47\u0e14\u0e25\u0e31\u0e1a\u0e20\u0e32\u0e29\u0e32\u0e41\u0e25\u0e30\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e23\u0e39\u0e49\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e04\u0e38\u0e13","publisher":{"@id":"https:\/\/engoo.co.th\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/engoo.co.th\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/engoo.co.th\/blog\/#organization","name":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39","url":"https:\/\/engoo.co.th\/blog\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","contentUrl":"https:\/\/assets.blog.engoo.com\/wp-content\/uploads\/sites\/4\/2020\/08\/10153535\/engoo-logo.svg","width":1,"height":1,"caption":"\u0e1a\u0e25\u0e47\u0e2d\u0e01\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e2d\u0e34\u0e07\u0e01\u0e39"},"image":{"@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/8305af459bc0f75be8a89fde54d6dfc5","name":"niicha","image":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/engoo.co.th\/blog\/#\/schema\/person\/image\/","url":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","contentUrl":"https:\/\/engoo.co.th\/blog\/wp-content\/uploads\/sites\/4\/2024\/01\/cropped-S__39026715-96x96.jpg","caption":"niicha"},"sameAs":["eye.engoochallenge@gmail.com\u00a0"],"url":"https:\/\/engoo.co.th\/blog\/author\/nichadaanantanithi\/"}]}},"_links":{"self":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/95","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/users\/420"}],"replies":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/comments?post=95"}],"version-history":[{"count":1,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/95\/revisions"}],"predecessor-version":[{"id":722,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/posts\/95\/revisions\/722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media\/96"}],"wp:attachment":[{"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/media?parent=95"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/categories?post=95"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/engoo.co.th\/blog\/wp-json\/wp\/v2\/tags?post=95"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}